{"id":120390,"date":"2021-08-05T18:40:28","date_gmt":"2021-08-06T01:40:28","guid":{"rendered":"https:\/\/barrazacarlos.com\/hashimoto-tiroidite\/"},"modified":"2023-05-23T16:13:55","modified_gmt":"2023-05-23T23:13:55","slug":"hashimoto-tiroidite","status":"publish","type":"post","link":"https:\/\/barrazacarlos.com\/it\/hashimoto-tiroidite\/","title":{"rendered":"Tiroidite di Hashimoto | La mia testimonianza di trattamento"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"120390\" class=\"elementor elementor-120390 elementor-119134\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4283a286 elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4283a286\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-38d9a5ea\" data-id=\"38d9a5ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f0f511b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f0f511b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-64a2d756\" data-id=\"64a2d756\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67c85634 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"67c85634\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f572b7f elementor-widget elementor-widget-heading\" data-id=\"4f572b7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:&quot;800&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tiroidite di Hashimoto | La mia testimonianza di trattamento<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab03292 elementor-widget elementor-widget-text-editor\" data-id=\"2ab03292\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIn questo post condivido cos&#8217;\u00e8 la tiroidite di Hashimoto, i sintomi, il trattamento che ho ricevuto, cosa ha funzionato e soprattutto cosa non ha funzionato.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5076e0c8 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"5076e0c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-372c1258\" data-id=\"372c1258\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e90693d elementor-widget elementor-widget-image\" data-id=\"1e90693d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/Tiroidite-di-Hashimoto-La-mia-testimonianza-di-trattamento-1024x576.jpg\" class=\"attachment-large size-large wp-image-119270\" alt=\"Tiroidite di Hashimoto La mia testimonianza di trattamento\" srcset=\"https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/Tiroidite-di-Hashimoto-La-mia-testimonianza-di-trattamento-1024x576.jpg 1024w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/Tiroidite-di-Hashimoto-La-mia-testimonianza-di-trattamento-300x169.jpg 300w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/Tiroidite-di-Hashimoto-La-mia-testimonianza-di-trattamento-768x432.jpg 768w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/Tiroidite-di-Hashimoto-La-mia-testimonianza-di-trattamento.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a33757e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a33757e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bc0846\" data-id=\"5bc0846\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4726daf6 elementor-widget elementor-widget-heading\" data-id=\"4726daf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Scritto da<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb8ccd4 elementor-align-left elementor-widget elementor-widget-post-info\" data-id=\"3bb8ccd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-ef43aea elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tCarlos Barraza\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-476dca5 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Agosto 5, 2021<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-6cd9597 elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<a href=\"https:\/\/barrazacarlos.com\/it\/category\/sviluppo-personale\/corpo-it\/\" class=\"elementor-post-info__terms-list-item\">Corpo<\/a>, <a href=\"https:\/\/barrazacarlos.com\/it\/category\/sviluppo-personale\/corpo-it\/hashimoto-it\/\" class=\"elementor-post-info__terms-list-item\">Hashimoto<\/a>, <a href=\"https:\/\/barrazacarlos.com\/it\/category\/sviluppo-personale\/\" class=\"elementor-post-info__terms-list-item\">Sviluppo personale<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55b46ad8 elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"55b46ad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\"><p class=\"wpml-ls-statics-post_translations wpml-ls\">Questo articolo \u00e8 disponibile anche in: \n<span role=\"navigation\">\n\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/\" hreflang=\"en\" lang=\"en\" class=\"wpml-ls-link\" aria-label=\"Passa a English\" title=\"Passa a English\"><span class=\"wpml-ls-native\">English<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-es wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/es\/\" hreflang=\"es\" lang=\"es\" class=\"wpml-ls-link\" aria-label=\"Passa a Espa\u00f1ol\" title=\"Passa a Espa\u00f1ol\"><span class=\"wpml-ls-native\">Espa\u00f1ol<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-de wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/de\/\" hreflang=\"de\" lang=\"de\" class=\"wpml-ls-link\" aria-label=\"Passa a Deutsch\" title=\"Passa a Deutsch\"><span class=\"wpml-ls-native\">Deutsch<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-it wpml-ls-current-language wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/it\/\" hreflang=\"it\" lang=\"it\" class=\"wpml-ls-link\" aria-current=\"page\" aria-label=\"Passa a Italiano\" title=\"Passa a Italiano\"><span class=\"wpml-ls-native\">Italiano<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-pt-br wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/pt-br\/\" hreflang=\"pt-br\" lang=\"pt-br\" class=\"wpml-ls-link\" aria-label=\"Passa a Portugu\u00eas\" title=\"Passa a Portugu\u00eas\"><span class=\"wpml-ls-native\">Portugu\u00eas<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-fr wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/fr\/\" hreflang=\"fr\" lang=\"fr\" class=\"wpml-ls-link\" aria-label=\"Passa a Fran\u00e7ais\" title=\"Passa a Fran\u00e7ais\"><span class=\"wpml-ls-native\">Fran\u00e7ais<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-ru wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/ru\/\" hreflang=\"ru\" lang=\"ru\" class=\"wpml-ls-link\" aria-label=\"Passa a \u0420\u0443\u0441\u0441\u043a\u0438\u0439\" title=\"Passa a \u0420\u0443\u0441\u0441\u043a\u0438\u0439\"><span class=\"wpml-ls-native\">\u0420\u0443\u0441\u0441\u043a\u0438\u0439<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-zh-hans wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/zh-hans\/\" hreflang=\"zh-hans\" lang=\"zh-hans\" class=\"wpml-ls-link\" aria-label=\"Passa a \u7b80\u4f53\u4e2d\u6587\" title=\"Passa a \u7b80\u4f53\u4e2d\u6587\"><span class=\"wpml-ls-native\">\u7b80\u4f53\u4e2d\u6587<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-nl wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/nl\/\" hreflang=\"nl\" lang=\"nl\" class=\"wpml-ls-link\" aria-label=\"Passa a Nederlands\" title=\"Passa a Nederlands\"><span class=\"wpml-ls-native\">Nederlands<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-pl wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/pl\/\" hreflang=\"pl\" lang=\"pl\" class=\"wpml-ls-link\" aria-label=\"Passa a polski\" title=\"Passa a polski\"><span class=\"wpml-ls-native\">polski<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-ar wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/ar\/\" hreflang=\"ar\" lang=\"ar\" class=\"wpml-ls-link\" aria-label=\"Passa a \u0627\u0644\u0639\u0631\u0628\u064a\u0629\" title=\"Passa a \u0627\u0644\u0639\u0631\u0628\u064a\u0629\"><span class=\"wpml-ls-native\">\u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-ja wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/ja\/\" hreflang=\"ja\" lang=\"ja\" class=\"wpml-ls-link\" aria-label=\"Passa a \u65e5\u672c\u8a9e\" title=\"Passa a \u65e5\u672c\u8a9e\"><span class=\"wpml-ls-native\">\u65e5\u672c\u8a9e<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-ro wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/ro\/\" hreflang=\"ro\" lang=\"ro\" class=\"wpml-ls-link\" aria-label=\"Passa a Rom\u00e2n\u0103\" title=\"Passa a Rom\u00e2n\u0103\"><span class=\"wpml-ls-native\">Rom\u00e2n\u0103<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-sv wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/sv\/\" hreflang=\"sv\" lang=\"sv\" class=\"wpml-ls-link\" aria-label=\"Passa a Svenska\" title=\"Passa a Svenska\"><span class=\"wpml-ls-native\">Svenska<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-id wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/id\/\" hreflang=\"id\" lang=\"id\" class=\"wpml-ls-link\" aria-label=\"Passa a Indonesia\" title=\"Passa a Indonesia\"><span class=\"wpml-ls-native\">Indonesia<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-ko wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/ko\/\" hreflang=\"ko\" lang=\"ko\" class=\"wpml-ls-link\" aria-label=\"Passa a \ud55c\uad6d\uc5b4\" title=\"Passa a \ud55c\uad6d\uc5b4\"><span class=\"wpml-ls-native\">\ud55c\uad6d\uc5b4<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-tr wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/tr\/\" hreflang=\"tr\" lang=\"tr\" class=\"wpml-ls-link\" aria-label=\"Passa a T\u00fcrk\u00e7e\" title=\"Passa a T\u00fcrk\u00e7e\"><span class=\"wpml-ls-native\">T\u00fcrk\u00e7e<\/span><\/a><\/span>\t<span class=\"wpml-ls-slot-post_translations wpml-ls-item wpml-ls-item-uk wpml-ls-last-item wpml-ls-item-legacy-post-translations\"><a href=\"https:\/\/barrazacarlos.com\/uk\/\" hreflang=\"uk\" lang=\"uk\" class=\"wpml-ls-link\" aria-label=\"Passa a \u0423\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u0430\" title=\"Passa a \u0423\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u0430\"><span class=\"wpml-ls-native\">\u0423\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u0430<\/span><\/a><\/span><\/span>\n<\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ffa685 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"1ffa685\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;collapse_subitems&quot;:&quot;yes&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;Non sono state trovate intestazioni in questa pagina.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tIndice\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__1ffa685\" aria-expanded=\"true\" aria-label=\"Apri l&#039;indice dei contenuti\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__1ffa685\" aria-expanded=\"true\" aria-label=\"Chiudi l&#039;indice dei contenuti\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__1ffa685\" class=\"elementor-toc__body elementor-toc__list-items--collapsible\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11f28e22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11f28e22\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51f1bff2\" data-id=\"51f1bff2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c3e2f02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c3e2f02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2321e8b0\" data-id=\"2321e8b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29c77b48 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"29c77b48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9aa33 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1c9aa33\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;800&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ho anche la tiroidite di Hashimoto.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e928aa9 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5e928aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se sei come me che hai cercato risposte e soluzioni, e devi chiedere a Google un Trattamento Hashimoto, allora spero che questo articolo ti aiuti come guida per sapere cosa fare.<\/p>\n<p>E se anche tu sei come me, \u00e8 perch\u00e9 i medici ti stanno lasciando senza le risposte che stai cercando e potrebbero aver detto che devi solo prendere levotiroxina per il resto della tua vita e questo \u00e8 tutto, non c&#8217;\u00e8 altro da fare.<\/p>\n<p>So quanto possa essere difficile essere alla ricerca di risposte che possano aiutarvi a ritrovare il vostro equilibrio, ma i medici convenzionali non vi aiutano, lasciandovi con una semplice risposta come &#8220;Mi dispiace, siete sotto stress&#8221; o &#8220;Se andate da un altro medico sar\u00e0 lo stesso&#8221;.<\/p>\n<p>Perch\u00e9 ho vissuto da sola e ho provato la sensazione di vergognarmi ogni volta che dovevo andare dal medico perch\u00e9 non mi sentivo bene, nonostante stessi gi\u00e0 prendendo la pillola di levotiroxina e i miei test TSH fossero &#8220;normali&#8221;.<\/p>\n<p>Forse non salver\u00f2 il mondo intero, ma se condividere la mia esperienza potrebbe aiutare a guidare persone come te a trovare almeno qualche idea di un buon e reale trattamento della tiroidite di Hashimoto, allora varr\u00e0 mille mondi.<\/p>\n<p>Quindi continua a leggere per saperne di pi\u00f9 su questa condizione autoimmune che c&#8217;\u00e8 speranza di ripristinare l&#8217;equilibrio nella tua vita.<\/p>\n<p>Non sono un medico e lo prendo come un consiglio, ci sto lavorando anche con un medico di medicina funzionale.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f0e72d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f0e72d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ed60c16\" data-id=\"ed60c16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-75d033e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75d033e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ec3f08e\" data-id=\"ec3f08e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-125d931 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"125d931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a72936b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a72936b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;800&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cos'\u00e8 la tiroidite di Hashimoto?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfd4a2d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dfd4a2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E voglio iniziare descrivendo cosa \u00e8 la tiroidite di Hashimoto e cosa non lo \u00e8.<\/p>\n<p>Come descritto dal <a href=\"https:\/\/drhyman.com\/blog\/2021\/03\/11\/podcast-hc47\/\" target=\"_blank\" rel=\"noopener\">Dr. Mark Hyman<\/a>, medico di medicina funzionale, la <em>tiroidite di Hashimoto \u00e8 una malattia autoimmune in cui il corpo attacca la ghiandola tiroidea e diminuisce la sua capacit\u00e0 di creare ormoni preziosi, che hanno un impatto su ogni cellula del corpo<\/em>.<\/p>\n<p><strong>Vale la pena ricordare che il problema di Hashimoto, non si basa solo sulla tiroide, ma anche nell&#8217;intestino e nel sistema immunitario.<\/strong><\/p>\n<p>Ed \u00e8 qui che il problema potrebbe iniziare per alcune persone a cui \u00e8 stato appena diagnosticato l&#8217;ipotiroidismo o l&#8217;ipertiroidismo.<\/p>\n<p>Descrivere l&#8217;ipotiroidismo vs Hashimoto \u00e8 davvero semplice, principalmente il primo presenta solo una bassa attivit\u00e0 tiroidea, mentre nell&#8217;Hashimoto \u00e8 il sistema immunitario che \u00e8 fuori controllo.<\/p>\n<p>Ma il fatto \u00e8 che nella maggior parte dei casi l&#8217;ipotiroidismo \u00e8 in realt\u00e0 un Hashimoto non scoperto, ma poich\u00e9 i medici non testano gli anticorpi come l&#8217;anticorpo perossidasi tiroidea (TPO) e gli autoanticorpi <em>tireoglobulina<\/em> (TGAB), in realt\u00e0 non notano il problema che c&#8217;\u00e8 dietro.<\/p>\n<p>Quindi, sicuramente, qualsiasi medico convenzionale, o anche gli endocrinologi potrebbero chiederti di testare solo T3, T4 e TSH e basta.<\/p>\n<p>Il tuo TSH potrebbe mostrare numeri al di sopra della gamma alta e il medico ti dir\u00e0, sei ipotiroidea, dovrai prendere 100 mg di levotiroxina e questo ti aiuter\u00e0 con i tuoi sintomi, torna tra 3 mesi per testare di nuovo per vedere se la dose \u00e8 giusta o dovremo regolare.<\/p>\n<p>Beh, lasciate che vi dica che sono stronzate!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5111385\" data-id=\"5111385\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a904b6 elementor-widget elementor-widget-image\" data-id=\"3a904b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/07\/inscription-tsh-with-products-and-ingredients-containing-vitamins-for-healthy-thyroid-1024x682.jpg\" class=\"attachment-large size-large wp-image-119146\" alt=\"Inscription TSH con prodotti e ingredienti contenenti vitamine per una tiroide sana\" srcset=\"https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/07\/inscription-tsh-with-products-and-ingredients-containing-vitamins-for-healthy-thyroid-1024x682.jpg 1024w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/07\/inscription-tsh-with-products-and-ingredients-containing-vitamins-for-healthy-thyroid-300x200.jpg 300w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/07\/inscription-tsh-with-products-and-ingredients-containing-vitamins-for-healthy-thyroid-768x512.jpg 768w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/07\/inscription-tsh-with-products-and-ingredients-containing-vitamins-for-healthy-thyroid-1536x1024.jpg 1536w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/07\/inscription-tsh-with-products-and-ingredients-containing-vitamins-for-healthy-thyroid.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf2e72a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf2e72a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2785e13f\" data-id=\"2785e13f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6210e6f7 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"6210e6f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62fa983d\" data-id=\"62fa983d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40cf844 elementor-hidden-phone elementor-widget elementor-widget-html\" data-id=\"40cf844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CR13Ye9B259\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CR13Ye9B259\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CR13Ye9B259\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">A post shared by Rachael \ud83e\udd8b Hashimotos Coach (@rach_hashimotoswellness)<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5597ef93\" data-id=\"5597ef93\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49b55bf elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"49b55bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73042b5a elementor-widget elementor-widget-heading\" data-id=\"73042b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sintomi della tiroidite di Hashimoto, appariranno anche prendendo la levotiroxina.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14e97d14 elementor-widget elementor-widget-text-editor\" data-id=\"14e97d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Poich\u00e9 mi \u00e8 stato diagnosticato un nodulo alla tiroide, ho dovuto fare diversi test che il mio primo endocrinologo mi ha solo impostato con una dose elevata di levotiroxina per &#8220;ridurre la dimensione del nodulo&#8221;.<\/p>\n<p>Ho iniziato a prendere pi\u00f9 di 125 mg, ma l&#8217;effetto era terribile!<\/p>\n<p>Ho avuto orribili tachicardie che non avevo mai avuto in vita mia.<\/p>\n<p>Quindi, primo suggerimento, se hai intenzione di prendere la levotiroxina, <strong>INIZIA DA UNA DOSE BASSA E AUMENTA GRADUALMENTE<\/strong>!<\/p>\n<p>Quindi avevo queste tachicardie, mi sentivo ansioso, non dormivo bene, mi cadevano i capelli, sentivo che stavo tremando.<\/p>\n<p>Quello \u00e8 stato un brutto periodo per me.<\/p>\n<p>Sono tornata dal medico, mi ha fatto il test per gli anticorpi e poi mi ha detto: hai la Hashimoto e continua a prendere 100 mg.<\/p>\n<p>Questo non ha risolto molto, allora ho deciso di andare da un altro medico che mi ha spiegato un po&#8217; meglio era Hashimoto.<\/p>\n<p>La prima volta \u00e8 stato amichevole, ma dato che andavo spesso con lui perch\u00e9 non mi sentivo bene, non \u00e8 stato molto amichevole e mi vergogno di nuovo con me stessa per non sentirmi bene nonostante stessi seguendo le istruzioni.<\/p>\n<p>Alcuni altri sintomi di Hashimoto che potresti avere sono i seguenti, come descritto da Rachael Webster, PharmD &amp; Hashimoto&#8217;s Coach.<\/p>\n<ol>\n<li>Colesterolo alto<\/li>\n<li>Aumento di peso<\/li>\n<li>Muscoli e articolazioni doloranti<\/li>\n<li>Perdita di capelli<\/li>\n<li>Gozzo (Allargamento della ghiandola tiroidea)<\/li>\n<li>Cambiamenti mestruali  <\/li>\n<li>Sensazione di freddo<\/li>\n<li>Pelle secca e unghie deboli<\/li>\n<li>Costipazione<\/li>\n<li>Battito cardiaco lento<\/li>\n<\/ol>\n<p>E potrebbero esserci altri sintomi di Hashimoto che possono apparire, ma questa \u00e8 solo una lista.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6511b7e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6511b7e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-379089c1\" data-id=\"379089c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-319aba5f elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"319aba5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-241f6e86 elementor-widget elementor-widget-heading\" data-id=\"241f6e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cosa causa la malattia di hashimoto?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f65ecec elementor-widget elementor-widget-text-editor\" data-id=\"f65ecec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E quando dopo aver chiesto al medico, potrebbe non esserci una risposta a questa domanda.<\/p>\n<p>Come diavolo ho fatto a prendere la tiroide di Hashimoto?<\/p>\n<p>E il vostro medico potrebbe non avere una spiegazione.<\/p>\n<p>E se cercate su internet troverete le seguenti risposte.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4dc31fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dc31fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5cac12a\" data-id=\"5cac12a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a474e70 elementor-widget elementor-widget-testimonial\" data-id=\"a474e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><p>La malattia di Hashimoto \u00e8 un disturbo autoimmune in cui il tuo sistema immunitario crea anticorpi che danneggiano la tiroide. I medici non sanno cosa provoca l'attacco alla tiroide da parte del sistema immunitario. Alcuni scienziati pensano che un virus o un batterio possa innescare la risposta, mentre altri credono che un difetto genetico possa essere coinvolto.<\/p>\n<p>Una combinazione di fattori - tra cui l'ereditariet\u00e0, il sesso e l'et\u00e0 - pu\u00f2 determinare la vostra probabilit\u00e0 di sviluppare il disturbo.<\/p>\n<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-testimonial-name\" href=\"https:\/\/www.mayoclinic.org\/diseases-conditions\/hashimotos-disease\/symptoms-causes\/syc-20351855\" target=\"_blank\" rel=\"noopener\">Clinica Mayo<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63363b2\" data-id=\"63363b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-125955a elementor-widget elementor-widget-testimonial\" data-id=\"125955a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><p>I ricercatori non sanno perch\u00e9 alcune persone sviluppano la malattia di Hashimoto, ma una storia familiare di malattia della tiroide \u00e8 comune. Diversi fattori possono giocare un ruolo, compresi i geni, i virus, come l'epatite C.<\/p>\n<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-testimonial-name\" href=\"https:\/\/www.niddk.nih.gov\/health-information\/endocrine-diseases\/hashimotos-disease\" target=\"_blank\" rel=\"noopener\">NIDDK<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9883881 elementor-widget elementor-widget-text-editor\" data-id=\"9883881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E come potete continuare a cercare sui &#8220;siti esperti e principali&#8221; non c&#8217;\u00e8 una risposta adeguata a questa domanda.<\/p>\n<p>Quindi come farete a lavorare sulla causa principale del vostro problema se non c&#8217;\u00e8 una risposta.<\/p>\n<p>E non stanno nemmeno menzionando un problema di Gut.<\/p>\n<p>La buona notizia \u00e8 che ci sono gi\u00e0 persone che trovano risposta per sapere cosa causa la tiroidite di Hashimoto.<\/p>\n<p><strong>E la tiroidite di Hashimoto non \u00e8 una tiroide disfunzionale di per s\u00e9, la tiroidite di Hashimoto \u00e8 causata dal fatto che il tuo intestino non sta proteggendo completamente il tuo corpo per fermare le tossine dal filtraggio del sangue.<\/strong><\/p>\n<p>Almeno questo \u00e8 quello che so.<\/p>\n<p><strong>Ho la mia teoria che l&#8217;uso di antibiotici e probabilmente altri farmaci da prescrizione stanno ovviamente influenzando il rivestimento dell&#8217;intestino e lo stanno trasformando in un intestino che perde, ma probabilmente i medici non racconteranno questa storia.<\/strong><\/p>\n<p>Il glutine dovrebbe essere eliminato da una dieta Hashimoto, poich\u00e9 ha la gliadina, una proteina che pu\u00f2 filtrare attraverso l&#8217;intestino al flusso sanguigno ed \u00e8 simile al tessuto tiroideo.<\/p>\n<p>Quindi, quando il sistema immunitario lavora contro questo, prender\u00e0 di mira anche il tessuto tiroideo perch\u00e9 \u00e8 simile ad esso, portando come conseguenza lo squilibrio tiroideo e ormonale.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ff8861 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ff8861\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61227ff\" data-id=\"61227ff\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d8365e elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7d8365e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5423bde elementor-widget elementor-widget-heading\" data-id=\"5423bde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per cos'altro si dovrebbe fare il test se si ha la tiroidite di Hashimoto?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d864450 elementor-widget elementor-widget-text-editor\" data-id=\"d864450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Come gi\u00e0 detto, il solo test di T3, T4 e TSH non \u00e8 sufficiente per scoprire se si ha la Hashimoto.<\/p>\n<p>Dovresti anche aver testato gli anticorpi della perossidasi tiroidea e gli autoanticorpi della tireoglobulina, giusto per confermare che si tratta di Hashimoto.<\/p>\n<p>Ma questo non \u00e8 sufficiente, perch\u00e9 non vi mostrer\u00e0 il quadro completo di ci\u00f2 che sta succedendo in altri livelli del vostro corpo.<\/p>\n<p>Nel mio percorso di visita a diversi medici, fino agli ultimi sono stato testato per alcuni altri fattori importanti che influenzano anche qualcuno che ha Hashimoto.<\/p>\n<p>Condivido quelli che erano rilevanti per me, ma potete anche chiedere al vostro medico se potreste essere gi\u00f9 per alcuni di questi.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a966b elementor-widget elementor-widget-heading\" data-id=\"d9a966b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vitamina D<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e02579 elementor-widget elementor-widget-text-editor\" data-id=\"1e02579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La cruciale e importante vitamina D.<\/p>\n<p>Mentre vivevo in Germania, e ho fatto il test per la vitamina D, in realt\u00e0 ero piuttosto basso.<\/p>\n<p>Una volta tornato qui in Messico, il mio medico di medicina funzionale non ha rifatto i test fino a diversi mesi dopo aver iniziato il trattamento con lui.<\/p>\n<p>La vitamina D gioca un ruolo cruciale nelle persone con malattie autoimmuni.<\/p>\n<p><em>Storicamente, la vitamina D \u00e8 stata associata alla regolazione del metabolismo osseo. Tuttavia, sempre pi\u00f9 prove dimostrano una forte associazione tra la segnalazione della vitamina D e molti processi biologici che regolano le risposte immunitarie. (<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6047889\/\" target=\"_blank\" rel=\"noopener\">Yang et al, 2013<\/a>)<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc7fcc9 elementor-widget elementor-widget-heading\" data-id=\"fc7fcc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vitamina B<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbfe957 elementor-widget elementor-widget-text-editor\" data-id=\"bbfe957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La vitamina B ha un altro test che ho fatto e che ero anche a bassi livelli.<\/p>\n<p>Inoltre, vale la pena ricordare che l&#8217;omocisteina potrebbe essere a livelli pi\u00f9 alti, quindi si potrebbe anche preferire di testare quello e sicuramente si dovr\u00e0 aumentare la vitamina B.<\/p>\n<p>Nei pazienti con ipotiroidismo autoimmune, la carenza di vit-D e vit-B12 dovrebbe essere indagata al momento della diagnosi e periodicamente nei follow-up. (<a href=\"https:\/\/www.karger.com\/Article\/FullText\/505094\" target=\"_blank\" rel=\"noopener\">Akta\u015f H.\u015e., 2020<\/a>)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ccded2 elementor-widget elementor-widget-heading\" data-id=\"8ccded2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zinco, rame, selenio<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8640a98 elementor-widget elementor-widget-text-editor\" data-id=\"8640a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zinco, rame e selenio sono menzionati per essere importanti per una buona funzione della tiroide.<\/p>\n<p>In uno studio, \u00e8 menzionato che la concentrazione nel sangue di oligoelementi essenziali, soprattutto il rapporto di rame e selenio pu\u00f2 influenzare direttamente la funzione tiroidea in pazienti con tiroidite di Hashimoto e ipotiroidismo palese. (<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/27793066\/\" target=\"_blank\" rel=\"noopener\">Milutinovic et al 2016<\/a>)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa8078e elementor-widget elementor-widget-heading\" data-id=\"aa8078e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pregnenolone<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba76dcd elementor-widget elementor-widget-text-editor\" data-id=\"ba76dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il pregnenolone \u00e8 un ormone prodotto naturalmente nel corpo dalla ghiandola surrenale. Il pregnenolone si ottiene anche dal colesterolo, ed \u00e8 il materiale di partenza nella produzione di testosterone, progesterone, cortisolo, estrogeni e altri ormoni. Poich\u00e9 il corpo lo usa biochimicamente come materiale di partenza, il pregnenolone viene talvolta definito &#8220;precursore&#8221; o &#8220;pro-ormone&#8221;. (<a href=\"https:\/\/www.usada.org\/spirit-of-sport\/education\/pregnenolone\/\" target=\"_blank\" rel=\"noopener\">USADA<\/a>)<\/p>\n<p>In realt\u00e0 non sapevo cosa fosse questo ormone e che esistesse.<\/p>\n<p>Il mio medico di medicina funzionale mi ha chiesto di fare un test per il Pregnenolone e, naturalmente, con mia grande sorpresa, era a un livello molto basso, cos\u00ec mi ha dato un supplemento di Pregnenolone.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fbc69f elementor-widget elementor-widget-heading\" data-id=\"7fbc69f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Test delle sensibilit\u00e0 alimentari per creare la tua dieta Hashimoto<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96383d7 elementor-widget elementor-widget-text-editor\" data-id=\"96383d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E probabilmente questo \u00e8 un altro dei test pi\u00f9 importanti da fare se hai la tiroidite di Hashimoto.<\/p>\n<p>Il fatto \u00e8 che in generale questo test potrebbe essere abbastanza costoso.<\/p>\n<p>Quindi, se andare in un laboratorio per testare le sensibilit\u00e0 alimentari e vedere quali alimenti creano una reazione anitica non \u00e8 un&#8217;opzione al momento, allora si pu\u00f2 iniziare creando una dieta di eliminazione.<\/p>\n<p>Ho fatto questo test in Germania, ma il mio medico qui in Messico avrebbe chiesto anche il test delle sensibilit\u00e0 alimentari.<\/p>\n<p>In generale, si raccomanda di lasciare fuori glutine, latticini e uova, ma ogni persona \u00e8 diversa e unica, e ci\u00f2 che potrebbe avere una reazione su di me, potrebbe non essere lo stesso per te, quindi ascolta il tuo corpo.<\/p>\n<p>Nel mio caso, la caseina, una proteina che si trova nei latticini, non era nella mia lista di reazioni, inoltre avere un bicchiere di latte magro per me non \u00e8 un problema.<\/p>\n<p>Qui condivido con voi la lista degli alimenti che ho reagito per gli anticorpi.<\/p>\n<p>Il gruppo 1 \u00e8 il cibo che posso mangiare quotidianamente. Il gruppo 2 \u00e8 cibo che potrei intercalare. Il gruppo 3 \u00e8 un alimento con reazione anticorpale moderata. Il gruppo 4 \u00e8 un alimento con un&#8217;alta reazione anticorpale.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142354 elementor-tabs-view-vertical elementor-tabs-alignment-center elementor-widget elementor-widget-global elementor-global-142354 elementor-widget-tabs\" data-id=\"142354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1311\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1311\" aria-expanded=\"false\">Group 1: Could be eaten daily<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1312\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1312\" aria-expanded=\"false\">Group 2: Could be intercalated<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1313\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1313\" aria-expanded=\"false\">Group 3: Medium Antibody reaction<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1314\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1314\" aria-expanded=\"false\">Group 4: High Antibody reaction<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1311\" aria-expanded=\"false\">Group 1: Could be eaten daily<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1311\" tabindex=\"0\" hidden=\"false\"><ul><li>Apple<\/li><li>Banana<\/li><li>Fajol, Buckwheat<\/li><li>Green Bean<\/li><li>Kiwi<\/li><li>Garlic<\/li><li>Corn<\/li><li>Rice<\/li><li>Beef<\/li><li>Soya Bean<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1312\" aria-expanded=\"false\">Group 2: Could be intercalated<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1312\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Avocado<\/li><li>Bread yeast<\/li><li>Cashew nuts<\/li><li>Dill<\/li><li>Duck<\/li><li>Strawberry<\/li><li>Chicken<\/li><li>Carrot<\/li><li>Potato<\/li><li>Casein<\/li><li>Cherry<\/li><li>Cumin<\/li><li>Cow Milk<\/li><li>Lamb<\/li><li>Linseed<\/li><li>Melon<\/li><li>Bell Pepper<\/li><li>Brazil Nut<\/li><li>Sheep&#8217;s milk<\/li><li>Black pepper<\/li><li>Pork<\/li><li>Celery<\/li><li>Spinach<\/li><li>Mare&#8217;s milk<\/li><li>Tomato<\/li><li>Vanilla<\/li><li>Walnuts<\/li><li>Grapes<\/li><li>Goat milk<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1313\" aria-expanded=\"false\">Group 3: Medium Antibody reaction<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1313\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Amaranth <\/li><li>Mushroom <\/li><li>Fennel <\/li><li>Millet <\/li><li>Cabbage <\/li><li>Parsley <\/li><li>Onion<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1314\" aria-expanded=\"false\">Group 4: High Antibody reaction<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1314\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Pineapple <\/li><li>Spelt <\/li><li>Cod <\/li><li>Pea <\/li><li>Peanut <\/li><li>Gluten <\/li><li>Oats <\/li><li>Hazelnut <\/li><li>Egg <\/li><li>Carob <\/li><li>Salmon <\/li><li>Lentil <\/li><li>Almond <\/li><li>Orange <\/li><li>Peach <\/li><li>Quinoa <\/li><li>Rye <\/li><li>Mustard <\/li><li>Sesame <\/li><li>Sunflower seeds <\/li><li>Tuna <\/li><li>Wheat<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d32db5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d32db5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5932602\" data-id=\"5932602\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f01349 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f01349\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cf013b5\" data-id=\"cf013b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc22c47 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cc22c47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a568ab4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a568ab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;800&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il mio piano di trattamento della tiroidite di Hashimoto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-309a86b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"309a86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ho fatto fatica a trovare un buon trattamento Hashimoto per me.<\/p>\n<p>Come ho gi\u00e0 detto, prendere la levotiroxina da sola non \u00e8 l&#8217;unica risposta, anche se hai un TSH normale.<\/p>\n<p>Se continuate a cercare sui principali siti web medici, dicono solo questo, ma non passano in rassegna le cause profonde.<\/p>\n<p>E mi sentivo cos\u00ec sola, senza alcuna speranza dopo essere andata tante volte dal medico e aver visto che il mio TSH era nella norma.<\/p>\n<p>Trovare alla fine un medico di medicina funzionale in Messico ha contribuito a migliorare la mia salute.<\/p>\n<p>Non posso dire di essere ancora al mio meglio, ma certamente sono migliorato e ci sto lavorando.<\/p>\n<p>Quindi quello che ti consiglio come trattamento Hashimoto \u00e8 di trovare le tue sensibilit\u00e0 alimentari e fare la tua dieta Hashimoto personalizzata.<\/p>\n<p>Siamo diversi, quindi potreste avere reazioni diverse a cibi diversi.<\/p>\n<p>Si raccomanda anche di prendere alcuni integratori Hashimoto.  <\/p>\n<p>Il mio medico mi ha raccomandato Throne Thyrocsin, che ha vitamina C, E, B12, iodio, zinco, selenio, rame, L-tirosina e Aschwaganda.<\/p>\n<p>Fate solo attenzione a dove comprate l&#8217;Aschwaganda, potrebbe essere mescolato con Rhodiola e Benzodiazepina, un farmaco per dormire, ho gi\u00e0 avuto alcune esperienze non comuni che condivider\u00f2 nel mio libro.<\/p>\n<p>Sto anche prendendo Thorne Methyl-Guard, che supporta la metilazione per la salute di cuore, vasi sanguigni, cervello e ossa.<\/p>\n<p>Tra alcuni altri integratori importanti c&#8217;\u00e8 quello di prendere la glutammina, che aiuta a rigenerare l&#8217;intestino.<\/p>\n<p>Non dimenticate di fare bagni di sole o di esporvi al sole, e prendete anche la vitamina D, io prendo anche la vitamina D\/K2 liquida della Thorne.  <\/p>\n<p>Questi sono quelli che prendo io, ma puoi anche provare a cercare i suplementi che meglio si adattano a te.<\/p>\n<p>Su quale dose di levotiroxina e quale marca \u00e8 meglio, ne discuta con il suo medico.<\/p>\n<p>Nel mio caso, la levotiroxina mi ha fatto pi\u00f9 male che bene.<\/p>\n<p>Ho provato Eutorix e Synthyroid e non mi hanno aiutato per niente, come detto, mi hanno portato palpitazioni, cattivo sonno e tremori.<\/p>\n<p>Ho provato a non prendere la pillola di levotiroxina, e per alcuni mesi mi sentivo meglio e dormivo molto meglio, ma ho iniziato ad avere dei problemi di circolazione alle gambe, e il medico mi ha ridato una bassa dose di levotiroxina, ma devo ancora scoprire cosa funziona meglio per me.<\/p>\n<p>Spero che questo come articolo di partenza vi aiuti, e mi propongo di avere qualche altro articolo relativo alla tiroidite di Hashimoto per scavare pi\u00f9 a fondo in questa discussione.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-583d7d9\" data-id=\"583d7d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7045bc3 elementor-widget elementor-widget-image\" data-id=\"7045bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/metal-spoons-of-various-gluten-free-flour-1024x682.jpg\" class=\"attachment-large size-large wp-image-119231\" alt=\"Cucchiai di metallo di varie farine senza glutine\" srcset=\"https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/metal-spoons-of-various-gluten-free-flour-1024x682.jpg 1024w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/metal-spoons-of-various-gluten-free-flour-300x200.jpg 300w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/metal-spoons-of-various-gluten-free-flour-768x512.jpg 768w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/metal-spoons-of-various-gluten-free-flour-1536x1024.jpg 1536w, https:\/\/barrazacarlos.com\/wp-content\/uploads\/2021\/08\/metal-spoons-of-various-gluten-free-flour.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bb69bd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bb69bd3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6beb30d2\" data-id=\"6beb30d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-569f65d1 elementor-widget elementor-widget-heading\" data-id=\"569f65d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Pi\u00f9 su <b>Body<\/b>.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-214002ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"214002ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e59119e\" data-id=\"3e59119e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Scritto da Este posto tamb\u00e9m est\u00e1 dispon\u00edvel em: English Espa\u00f1ol Deutsch Italiano Portugu\u00eas Fran\u00e7ais \u0420\u0443\u0441\u0441\u043a\u0438\u0439 \u7b80\u4f53\u4e2d\u6587 Nederlands polski \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u65e5\u672c\u8a9e Rom\u00e2n\u0103 Svenska Indice Ho anche la tiroidite di Hashimoto. Se sei come me che hai cercato risposte e soluzioni, e devi chiedere a Google un Trattamento Hashimoto, allora spero che questo articolo ti aiuti come [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":119270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1585,1586,2296],"tags":[1587],"class_list":["post-120390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sviluppo-personale","category-corpo-it","category-hashimoto-it","tag-hashimoto-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/posts\/120390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/comments?post=120390"}],"version-history":[{"count":0,"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/posts\/120390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/media\/119270"}],"wp:attachment":[{"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/media?parent=120390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/categories?post=120390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/barrazacarlos.com\/it\/wp-json\/wp\/v2\/tags?post=120390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}